{"id":451,"date":"2015-02-08T18:42:30","date_gmt":"2015-02-08T17:42:30","guid":{"rendered":"http:\/\/www.cotedenuits.fr\/?page_id=451"},"modified":"2026-01-11T18:37:17","modified_gmt":"2026-01-11T17:37:17","slug":"descriptif-de-cote-de-nuits","status":"publish","type":"page","link":"https:\/\/www.cotedenuits.fr\/pt\/categorie-1\/descriptif-de-cote-de-nuits\/","title":{"rendered":"Descriptif de C\u00f4te de Nuits"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COQUE\u00a0 ET PONT<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Construction aluminium AGE MC 111 (AG4) en forme \u00e0 structure mixte, lisses en T\u00e9 et couples transversaux. Soudures \u00e0 l&#8217;argon Roof panoramique. Jupe arri\u00e8re latt\u00e9e de teck. Cloison avant\u00a0 \u00e9tanche. Coffre \u00e0 voile et \/ou large baille \u00e0 mouillages \u00e0 l&#8217;avant. Puits \u00e0 cha\u00eene pour deux mouillages. 2 coffres arri\u00e8res. 1 vaste soute dans cockpit. D\u00e9rive profil\u00e9e en aluminium avec syst\u00e8me de relevage \u00e0 palan sur winch. Safran aluminium relevable avec s\u00e9curit\u00e9 chocs. Barre \u00e0 roue <em>Witlook <\/em>avec compas de route SUNTO. Barre franche de secours. M\u00e8che de safran en plein d&#8217;aluminium de 5mm et crapaudine sur roulement \u00e0 billes. \u00c9pontille de m\u00e2t renforc\u00e9e. Cad\u00e8nes en aluminium \u00e9pais (12mm) soud\u00e9es et encastr\u00e9es dans la structure. Ferrure d&#8217;\u00e9trave soud\u00e9e et encastr\u00e9e avec deux daviers en inox. Anneaux d&#8217;\u00e9talingue dans le puits \u00e0 cha\u00eene. Mains courantes recouvertes de teck massif. Chandeliers en aluminium plein profil\u00e9 <em>Go\u00eft<\/em>. Balcons avant et arri\u00e8re en tubes d&#8217;aluminium. Pavois (rail de fargue) en profil d&#8217;aluminium perfor\u00e9 <em>Go\u00eft<\/em>. Bossoirs (Davit) en acier inoxydable (pour suspendre une annexe). Support en teck massif pour fixer un moteur &#8220;hors-bord&#8221;. Echelle de bain inox. Annexe BOMBARD (2010), moteur d\u2019annexe 4 cv 2 temps EVINRUDE (ancien).<\/p>\n<p style=\"text-align: justify;\"><strong><em>FERMETURE DU BATEAU<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">3 capots de pont, \u00e9coutilles <em>Barbarossa<\/em> ouvrant dans les deux sens avec moustiquaire int\u00e9rieure. 4 hublots de coque fixes. 3 hublots ouvrant <em>Go\u00eft<\/em> dans le cockpit avec moustiquaire int\u00e9rieure. Roof panoramique et panneau de descente avec moustiquaires ajustables. (tous chang\u00e9s par du Plexiglass Fum\u00e9 teint\u00e9 Gris de 10mm en Ao\u00fbt 2025). 2 manches \u00e0 air avec boite dorade sur roof. Une capote de descente et un bimini\u00a0 refaits en 2010 et r\u00e9vis\u00e9s r\u00e9guli\u00e8rement. Liaison capote &#8211; bimini possible par visi\u00e8re transparente ou toile identique au bimini et \u00e0 la capote avec fermetures zip.<\/p>\n<p style=\"text-align: justify;\">Vannes en <em>PVC<\/em> mont\u00e9es sur tube d&#8217;aluminium au dessus de la flottaison. Pinoches \u00e0 proximit\u00e9 de toutes les vannes.<\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00c9QUIPEMENTS SP\u00c9CIFIQUES<\/em><\/strong><strong>\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\">6 taquets d&#8217;amarrage et 6 chaumards. 4 points d&#8217;attaches pour lignes de vie en tresse de nylon (amovibles). 2 r\u00e9servoirs d&#8217;eau douce (150l x 2) en aluminium inclus dans les fonds. 1 r\u00e9servoir de fuel (110l) en aluminium inclus dans les fonds. Trappes de visite sur chacun des r\u00e9servoirs.<\/p>\n<h5 style=\"text-align: justify;\"><em><strong>Mat\u00e9riel de s\u00e9curit\u00e9 :<\/strong> <\/em><\/h5>\n<ul>\n<li style=\"text-align: justify;\">Six ceintures de sauvetage automatiques avec longes.<\/li>\n<li style=\"text-align: justify;\">Une Trousse de secours offshore ainsi que de nombreux mat\u00e9riels m\u00e9dicaux.<\/li>\n<li style=\"text-align: justify;\">Un Radeau de sauvetage 6 places PLASTIMO TRANSOCEAN (achat 2009 et r\u00e9vis\u00e9 r\u00e9guli\u00e8rement, derni\u00e8re r\u00e9vision en juin 2024).<\/li>\n<li>Balise de d\u00e9tresse EPIRB1\u00a0 RESCUEME neuve Ao\u00fbt 2023 qui remplace la Sarsat-Cospas bi-fr\u00e9quence, 406 et 121,5 MHz arriv\u00e9e en fin de vie pour cause d&#8217;arr\u00eat du remplacement de la batterie (encore \u00e0 bord pour l&#8217;instant)<\/li>\n<li>Une combinaison de survie TPS\u00a0 Guy Cotten.<\/li>\n<li>Deux lampes brassard flash individuelles + 5 ou 6 lampes de gilet feu flash \u00e0 d\u00e9clenchement manuel Plastimo<\/li>\n<li>Perche IOR avec feu de signalisation.<\/li>\n<li>Bou\u00e9e fer \u00e0 cheval avec cordage flottant et lampe flash \u00e0 retournement.<\/li>\n<li>Life Line avec lampe flash \u00e0 retournement.<\/li>\n<li>deux lignes de vie chang\u00e9e en ao\u00fbt 2023<\/li>\n<li>Echelle de bain en inox.<\/li>\n<\/ul>\n<h5 style=\"text-align: justify;\"><em>Un portique arri\u00e8re support d\u2019antennes<\/em><\/h5>\n<p style=\"text-align: justify;\"><em><strong>Divers \u00e9quipements sp\u00e9cifiques<\/strong> sont \u00e9galement inclus tels que : amarres, d\u00e9fenses, bou\u00e9e de sauvetage avec cordage flottant, life line avec feu \u00e0 \u00e9clats, perche IOR, ceintures de sauvetage automatiques, lot divers d&#8217;\u00e9quipement de s\u00e9curit\u00e9 (fus\u00e9es de d\u00e9tresse, etc.), corne de brume avec rechanges de gaz 4 extincteurs, couverture anti feu&#8230; Nombreuses pi\u00e8ces de rechange pour moteur (injecteur, pompe \u00e0 eau et rotors de rechange, pompe \u00e0 GO \u00e9lectrique&#8230;), une garniture de tube \u00e9tambot sp\u00e9ciale bateau aluminium, un joint tournant Progress PPS complet (l\u2019\u00e9tanch\u00e9it\u00e9 du PSS se fait par un plan de joint cr\u00e9\u00e9 entre les surfaces lisses d\u2019un rotor inox tournant avec l\u2019arbre et d\u2019un plateau carbone fixe, le stator), nombreuses pi\u00e8ces d&#8217;accastillage,\u00a0 1 pompe de cale \u00e9lectrique de rechange etc.<\/em><\/p>\n<p><strong>Jerricans :<\/strong> Deux jerricans orange pour le GO de 7 US Gallon soit 26,5 litres, un jerrican rouge de 25 litres pour Ess ou GO, 2 jerricans bleu pour l&#8217;eau potable. Tous ces jerricans peuvent \u00eatre accroch\u00e9s sur le pont pour des longues travers\u00e9es.<\/p>\n<p><strong>Pavillons<\/strong> divers tels qu&#8217;Espagne, Portugal, Hollande, Royaume Uni, USA, Belgique, Cuba, R\u00e9publique Dominicaine, Jama\u00efque, Saint Vincent et Grenadines, Dominique, Ste Lucie, Grenade et Carriacou), St Kitts et Nevis etc.<\/p>\n<p style=\"text-align: justify;\"><strong><em>PONT ET COCKPIT<\/em><\/strong><strong>\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\">Le pont a \u00e9t\u00e9 refait (2020\/2021), les plaques d&#8217;antid\u00e9rapant <em>Trade Master <\/em>ont \u00e9t\u00e9 enlev\u00e9es et remplac\u00e9es par la peinture antid\u00e9rapante blanche KiwiGrip. Le cockpit est garni d&#8217;un caillebotis en teck amovible et les bancs sont en lattes de teck massif. Ils sont totalement et facilement amovibles pour le nettoyage, reste la peinture du cockpit \u00e0 refaire. Jupe AR repeinte.<\/p>\n<p style=\"text-align: justify;\"><strong><em>MOTORISATION<\/em><\/strong><strong>\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\"><em>VOLVO 2003<\/em> diesel \u00e0 injection directe, 4 temps, 3 cylindres, soupapes en t\u00eate. Vilebrequin \u00e0 3 paliers surdimensionn\u00e9s. Pompe d&#8217;injection avec r\u00e9gulateur centrifuge. Transmission R directe avec arbre de 25mm. \u00c9tancheur d&#8217;arbre d&#8217;h\u00e9lice <em>PSS<\/em> mont\u00e9 sur arbre <em>(install\u00e9 en 2000)<\/em>. H\u00e9lice aluminium avec coupe orin. Accouplement souple et isol\u00e9. Alternateur de 70 amp\u00e8res, 600w avec r\u00e9gulateur de tension. R\u00e9partiteur de charge (syst\u00e8me double diode). D\u00e9marreur \u00e9lectrique puissance 0,8kw (1,1 ch.) chang\u00e9 en 2010. Syst\u00e8me de d\u00e9marrage manuel avec poign\u00e9e de d\u00e9compression. Tableau de bord moteur avec : cl\u00e9 de contact, thermom\u00e8tre eau, t\u00e9moin de charge et de pression d&#8217;huile, contr\u00f4le d&#8217;\u00e9clairage du tableau, du ventilateur de compartiment moteur.<\/p>\n<p style=\"text-align: justify;\"><em>Le moteur \u00e0 3824 heures au 2 mars 2023 .<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00c9LECTRICIT\u00c9<\/em><\/strong><strong>\u00a0 (Autres d\u00e9tails : voir la page<a title=\"Les \u00e9quipements de \u00ab\u00a0C\u00f4te de Nuits\u00a0\u00bb\" href=\"http:\/\/www.cotedenuits.fr\/page-categorie-2\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Les \u00e9quipements de C\u00f4te de Nuits<\/a>)<\/strong><\/p>\n<p style=\"text-align: justify;\">Deux tableaux \u00e9lectriques : un \u00e0 la table \u00e0 carte avec 8 dirupteurs thermiques et voyants de marche (lucioles). Le tableau comprend : 2 voltm\u00e8tres, 1 amp\u00e8rem\u00e8tre, 1 compteur d&#8217;heures moteur, 2 prises 12 volts (am\u00e9ricaines et europ\u00e9ennes) et un autre tableau dans la cabine AR pour l&#8217;alimentation du GPS ext, le moteur de la cuve \u00e0 eaux noires, le dessalinisateur (reste un de libre). Syst\u00e8me de contr\u00f4le et <em>moniteur de batteries<\/em><em>\u00a0NASA Batterie &#8211; BM1 Plus <\/em>affichant pour chaque groupe de batteries : voltage, amp\u00e9rage, consommation, charge&#8230; <em>(install\u00e9 en 2021).<\/em> Une batterie moteur Uship sp\u00e9ciale Marine de 12 V \/ 75 A. <em>(remplac\u00e9e en 2021),<\/em> 4 batteries de service 12V \/ 55A. soit un total de 220 Ah. <em>( remplac\u00e9es en 2010), 2<\/em> panneaux solaires Wechline Black Cristal de 120 w chacun, <span style=\"text-decoration: underline;\">ce qui donne une autonomie compl\u00e8te, r\u00e9frig\u00e9ration incluse avec un ensoleillement normal<\/span>), 1 r\u00e9gulateur de charge MPPT pour les panneaux solaires de 20A. 1 inverseur\/coupleur de batteries \u00e9tanche. 2 coupe-batteries bipolaires \u00e9tanches. 1 syst\u00e8me de contr\u00f4le\/coupure du gaz Propane ou Butane avec sol\u00e9no\u00efde. 1 chargeur de quai pour deux (voir 3) groupes de batteries <em>Dolphin<\/em> de 25 AH (110 ou 220 V) remplac\u00e9 en d\u00e9c 2020. Interrupteur de contr\u00f4le sur le tableau \u00e9lectrique avec contr\u00f4le de polarit\u00e9 et 2 prises 220V avec disjoncteur (coin cuisine et navigation). Tous les \u00e9clairages : cuisine, navigation, cabinet de toilette, cabine avant, cabine arri\u00e8re, carr\u00e9, coin cuisine sont \u00e9quip\u00e9s d&#8217;ampoules \u00e0 leds. L&#8217;\u00e9clairage de table \u00e0 carte est orientable et r\u00e9glable et \u00e9quip\u00e9 d&#8217;une ampoule \u00e0 leds de couleur rouge. 3 pompes de calles \u00e9lectriques avec flotteur pour d\u00e9marrage automatique. Pompe \u00e0 eau douce \u00e9lectrique avec vase d&#8217;expansion. Ventilateur de compartiment moteur. Hotte \u00e9lectrique 2 vitesses <em>V\u00e9tus <\/em>au dessus de la cuisini\u00e8re. 2 ventilateurs (cabine avant, table \u00e0 carte, carr\u00e9, cuisine).<\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00c9LECTRONIQUE (Autres d\u00e9tails : voir la page<a title=\"Les \u00e9quipements de \u00ab\u00a0C\u00f4te de Nuits\u00a0\u00bb\" href=\"http:\/\/www.cotedenuits.fr\/page-categorie-2\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Les \u00e9quipements de C\u00f4te de Nuits<\/strong><\/a><strong>)<\/strong><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Raymarine Autohelm ST50 Tridata<\/em> (sondeur, loch, distance, temp\u00e9rature de l&#8217;eau etc&#8230;) <em>Autohelm ST50 R\u00e9p\u00e9titeur<\/em> de table \u00e0 carte (toutes les fonctions du Tridarta). Girouette ST60. GPS <em>Garmin 75<\/em> avec possibilit\u00e9 de 250 &#8220;way point&#8221; <em>(&#8220;upgrad\u00e9&#8221;\u00a0 par Garmin en 2002)<\/em> Radar <em>Raytheon R10X<\/em>\u00a0 \u00e9cran cathodique, port\u00e9 1\/8 \u00e0 24 nm avec alarmes, EBL, VRM etc&#8230; Le radar est interfac\u00e9 avec le GPS et le pilote automatique (toutes les donn\u00e9es apparaissent sur l&#8217;\u00e9cran radar).<\/p>\n<p style=\"text-align: justify;\">Pilote automatique\u00a0<em>Raymarine ST4000+<\/em> pour barre \u00e0 roue. Le pilote est interfac\u00e9 avec le GPS.<\/p>\n<p style=\"text-align: justify;\">Ordinateur de bord fixe, sans ventilateur, Dual Core 1,6 GHz, disque dur 80GB Intel X25-M Solid State Drive SSD SSDSA2MO080G2R5, Lecteur DVD USB externe. Logiciel de navigation ScanNav interfac\u00e9 avec GPS, AIS&#8230; Cartes marine Navionics Europe avec Canaries, Mad\u00e8re et Acores et cartes SHOM Bretagne \/ Mer du Nord et Atlantique. Deux \u00e9crans dont un d\u00e9port\u00e9 Lilliput de faible consommation \u00e9lectrique.<\/p>\n<p style=\"text-align: justify;\"><strong><em>M\u00c2T ET GR\u00c9EMENT<\/em><\/strong><strong>\u00a0 (Autres d\u00e9tails : voir la page<a title=\"Les \u00e9quipements de \u00ab\u00a0C\u00f4te de Nuits\u00a0\u00bb\" href=\"http:\/\/www.cotedenuits.fr\/page-categorie-2\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Les \u00e9quipements de C\u00f4te de Nuits<\/strong><\/a><strong>)<\/strong><\/strong><\/p>\n<p style=\"text-align: justify;\">M\u00e2t <em>Z Spars<\/em>\u00a0 en profil d&#8217;aluminium de 7kgs\/m avec deux \u00e9tages de barres de fl\u00e8che et \u00e9chelons de mat inox. Le m\u00e2t est \u00e9quip\u00e9 de : 4 r\u00e9as en t\u00eate, 1 prise de poulie pour drisse de spi, 1 balancine, d&#8217;un winch pour prise de ris et \u00e9tarquage de la grand voile, feux de route (tricolore) et de mouillage (blanc) et projecteur de pont, girouette \u00e9lectronique Raymarine + girouette <em>Windex<\/em> et antenne VHF en t\u00eate de m\u00e2t. B\u00f4me <em>Z Spars<\/em> avec syst\u00e8me de prise de ris rapides, \u00e9quip\u00e9e de 6 pontets. Gr\u00e9ement en inox 18\/12 mono toron 19&#215;1 de 7 et 8mm de diam\u00e8tre dont : 1 \u00e9tai fixe (pour enrouleur Profurl C350 chang\u00e9 en 2008 avec cardan en t\u00eate), 1 \u00e9tai largable (pour foc Solent) diam 8mm, 2 bas-haubans (diam 8mm), 1 pataras r\u00e9glable par ridoir \u00e0 volant <em>Barbarossa <\/em>servant aussi d&#8217;antenne pour la BLU (diam 8mm), 2 interm\u00e9diaires (diam\u00e8tre 7mm chang\u00e9s en juillet 2014), 1 &#8220;baby stay&#8221;, r\u00e9glable par ridoir \u00e0 volant <em>Barbarossa<\/em>. Le gr\u00e9ement courant comprend : 3 \u00e9coutes (grand voile et g\u00e9nois), 4 drisses (grand voile chang\u00e9 en ao\u00fbt 2023, g\u00e9nois, foc Solent chang\u00e9e en ao\u00fbt 2023 et spi), 1 balancine de b\u00f4me, 1 palan pour le relevage de la d\u00e9rive, 1 tangon en aluminium \u00e9quip\u00e9 avec balancine (hale-haut), 1 retenue frein de b\u00f4me <em>Walder<\/em>. Un bout dehors r\u00e9tractable en inox renforc\u00e9 pour utilisation avec le spi asym\u00e9trique. 6 bloqueurs spinlock \u00e0 tribord et 5 bloqueurs Spinlock \u00e0 babord.<\/p>\n<p style=\"text-align: justify;\"><em>Toutes les drisses sont remplac\u00e9es r\u00e9guli\u00e8rement, certaines sont \u00e9quip\u00e9es de mousqueton en inox &#8220;Gibbs&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>ACCASTILLAGE DE PONT<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Six winchs de marque <em>Lewmar<\/em> dont 2 winches No 42ST pour \u00e9coutes de g\u00e9nois, 2 winches No 30 pour \u00e9coute de grand voile et drisses de grand voile\/relevage de d\u00e9rive\/retenue de b\u00f4me, 1 winch No 9 pour prise de ris et \u00e9tarquage de grand voile, 1 petit winch ST pour man\u0153uvre de l&#8217;enrouleur. 2 manivelles autobloquantes <em>Lewmar <\/em>pour winchs<em>.<\/em> 1 manivelle standard pour prises de ris. Syst\u00e8me de poulies sur les chandeliers pour le contr\u00f4le de l&#8217;enrouleur depuis le cockpit. 2 ensembles de 4 et 6 taquets coinceurs \u00e0 cames. 2 renvois doubles de poulies \u00e0 plat pont pour drisses. 1 rail d&#8217;\u00e9coute avec 2 chariots coupl\u00e9s <em>Lewmar<\/em> pour grand voile. 2 rails d&#8217;\u00e9coute <em>Barbarossa<\/em> avec poulies avale-tout pour \u00e9coutes de g\u00e9nois. 1 rail d&#8217;\u00e9coute avec chariot <em>Barbarossa<\/em> pour foc Solent auto vireur.<\/p>\n<p style=\"text-align: justify;\">Guindeau \u00e9lectrique (neuf)\u00a0 <strong>Lofrans Cayman 88<\/strong> &#8211; 1000W avec barbotin pour chaine de 10mm. Ancre Rocna anti-retournement galvanis\u00e9e 15Kg et 60 m\u00e8tres de cha\u00eene calibr\u00e9e ISO de 10mm, Main de fer Wichard, Jonction de cha\u00eene &#8211; ancre Kong ; commandes \u00e9lectriques \u00e0 l&#8217;avant &#8211; installation 2016, utilis\u00e9 une fois depuis l&#8217;installation en ao\u00fbt 2023. <i>Le mouillage est compl\u00e9t\u00e9 par 30m (100&#8242;) de cordage nylon trois brins.<\/i><\/p>\n<p style=\"text-align: justify;\">Ancre secondaire de 25lbs <em>Danforth<\/em> avec 30m (100&#8242; ) de chaine <em>&#8220;Hight Test&#8221;<\/em> de 8mm <em>(remplac\u00e9e en 2004).<\/em> <em>Le mouillage est compl\u00e9t\u00e9 par 30m (100&#8242;) de cordage nylon trois brins.<\/em><\/p>\n<p>Bout de remorquage \u00e0 poste dans la baille de mouillage.<\/p>\n<p style=\"text-align: justify;\"><strong><em>VOILURE (Autres d\u00e9tails : voir la page<a title=\"Les \u00e9quipements de \u00ab\u00a0C\u00f4te de Nuits\u00a0\u00bb\" href=\"http:\/\/www.cotedenuits.fr\/page-categorie-2\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Les \u00e9quipements de C\u00f4te de Nuits<\/strong><\/a><strong>)<\/strong><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Grand-voile latt\u00e9e de 28m2 avec 3 bandes de prises de ris et un ris de fond (r\u00e9vis\u00e9e totalement en mai 2022). G\u00e9nois <strong>Delta Voiles\u00a0<\/strong>sp\u00e9cial enrouleur de 42m\u00b2 (2007) avec bande UV rouge chang\u00e9e en 2020 (r\u00e9vis\u00e9 en mai 2022), nerf de chute, marques d&#8217;enroulement et penons. Foc Solent auto-vireur de 25m2 avec une bande de ris et bande de profil. Tourmentin de 6m\u00b2, spi asym\u00e9trique de 91m\u00b2 (2010), ancien solent avec une bande ris modifi\u00e9 avec coulisseaux pour remplacer la GV en cas de probl\u00e8me. Nombreuses \u00e9coutes de rechange.<\/p>\n<p>Lazy-bag \/ housse de grand voile et &#8220;pares soleils&#8221; pour les panneaux de pont.<\/p>\n<p style=\"text-align: justify;\"><strong><em>AM\u00c9NAGEMENT INT\u00c9RIEUR (plus de photos disponibles dans la page &#8221;Galerie photo&#8221;)<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Cabine avant :<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-490 alignright\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg\" alt=\"20025\" width=\"197\" height=\"128\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025.jpg 560w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Un lit breton pour deux adultes (190x160cm) avec d&#8217;importants rangements sous la couchette (4 coffres cloisonn\u00e9s). \u00c9quipets b\u00e2bord et tribord. Cette cabine est s\u00e9par\u00e9e du carr\u00e9 par un rideau et a\u00e9r\u00e9e par une vaste \u00e9coutille de 500x500cm. Matelas de couchette en mousse de 10cm.<\/p>\n<p style=\"text-align: justify;\"><strong>Cabine arri\u00e8re :<\/strong><\/p>\n<p style=\"text-align: justify;\">Situ\u00e9e \u00e0 b\u00e2bord au pied de la descente, comprend une couchette double de 190x160cm utilisable par 2 adultes. Vastes coffres de rangement sous la couchette et acc\u00e8s au syst\u00e8me de transmission du moteur, batteries etc. Penderie \u00e0 v\u00eatements, placard<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170004.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-493\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170004-300x199.jpg\" alt=\"04170004\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170004-300x199.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170004.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170003.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-492\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170003-300x199.jpg\" alt=\"04170003\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170003-300x199.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/04170003.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> \u00e0 chaussures et 4 tiroirs se trouvent dans la partie avant de la cabine. Matelas de couchette en mousse de 10cm. Plancher avec moquette. A\u00e9ration par hublot ouvrant de 340x140cm.<\/p>\n<p style=\"text-align: justify;\"><strong>Carr\u00e9 :<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c9quip\u00e9 d&#8217;une banquette confortable sur trois c\u00f4t\u00e9s avec dossiers anatomiques. Table<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20023.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-489 alignleft\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20023-300x195.jpg\" alt=\"20023\" width=\"196\" height=\"127\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20023-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20023.jpg 560w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20024.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-565 alignright\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20024-300x195.jpg\" alt=\"20024\" width=\"196\" height=\"127\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20024-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20024.jpg 560w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a> centrale \u00e0 deux battants avec fargues. 6 coffres cloisonn\u00e9s sous les banquettes. \u00c9quipets b\u00e2bord et tribord avec biblioth\u00e8que, bar,\u00a0\u00a0autoradio avec lecteur CD et MP3 avec portes coulissantes. A\u00e9ration par 2 panneaux ouvrants de 450x320cm. Plancher amovible en teck rainur\u00e9. Pendule, 2 barom\u00e8tres, horloge \u00e0 mar\u00e9e.<\/p>\n<p style=\"text-align: justify;\"><strong>Coin cuisine :<\/strong><\/p>\n<p style=\"text-align: justify;\">En forme de U comprenant : Cuisini\u00e8re \u00e0 gaz butane (ou propane) deux feux <em>&#8220;Plastimo&#8221;<\/em> avec four (chang\u00e9e en 2010), mont\u00e9e sur cardan + 2 bouteilles de 10kg Viseo butane de Butagaz en r\u00e9sine (6,6kg vide et 16,6kg pleines), \u00e9lectrovanne de s\u00e9curit\u00e9. Hotte aspirante \u00e9lectrique <em>&#8220;V\u00e9tus&#8221;<\/em> au dessus de la cuisini\u00e8re. 2 \u00e9viers inox avec robinet double eau chaude et eau froide. Glaci\u00e8re en acier<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20022.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-488 alignleft\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20022-300x195.jpg\" alt=\"20022\" width=\"180\" height=\"117\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20022-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20022.jpg 560w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a> inoxydable (60l environ). R\u00e9frig\u00e9rateur avec bac \u00e0 gla\u00e7ons et \u00e0 tr\u00e8s faible consommation . Nombreux<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20020.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-564 alignright\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20020-300x195.jpg\" alt=\"20020\" width=\"170\" height=\"110\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20020-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20020.jpg 560w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" \/><\/a> rangements pour vaisselle et accessoires de cuisines. Casier \u00e0 bouteilles ferm\u00e9. Rangements \u00e0 couverts. Planche \u00e0 d\u00e9couper sur plan de travail. A\u00e9ration par panneau ouvrant de 450x320cm.<\/p>\n<p style=\"text-align: justify;\"><strong>Coin navigation :<\/strong><\/p>\n<p style=\"text-align: justify;\">Dans le sens de la marche comprenant : Table \u00e0 carte<a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20017.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-487 alignright\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20017-300x195.jpg\" alt=\"20017\" width=\"183\" height=\"119\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20017-300x195.jpg 300w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20017.jpg 560w\" sizes=\"auto, (max-width: 183px) 100vw, 183px\" \/><\/a> format Grand Aigle. Pupitre pour rangement des cartes avec \u00e9cran ordinateur incorpor\u00e9. Si\u00e8ge navigateur en latte de ch\u00eane faisant aussi office de coffre pour les\u00a0 batteries de services (acc\u00e8s facile aux batteries pour inspection et entretien).<\/p>\n<p style=\"text-align: justify;\"><strong>Coin toilette :<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-563 alignleft\" src=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20019-195x300.jpg\" alt=\"20019\" width=\"147\" height=\"226\" srcset=\"https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20019-195x300.jpg 195w, https:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/04\/20019.jpg 242w\" sizes=\"auto, (max-width: 147px) 100vw, 147px\" \/><\/a>Situ\u00e9 \u00e0 tribord au pied de la descente comprend : WC marin manuel Twist&#8217;n&#8217;lock Jabsco (chang\u00e9 en 2012). R\u00e9servoir eaux noires avec vanne 3 voies et pompe \u00e9lectrique pour vidange (jamais utilis\u00e9). Lavabo en inox avec robinet double. Robinet s\u00e9par\u00e9 pour douche t\u00e9l\u00e9phone. Placard de rangement sous le lavabo 3 \u00e9quipets de rangement ferm\u00e9s par portes coulissantes au dessus de la toilette et du comptoir. Distributeur de papier, miroir et porte-serviettes. Chauffe-eau au gaz butane ou propane fournissant l&#8217;eau chaude sur l&#8217;\u00e9vier de cuisine, le lavabo et la douche. A\u00e9ration par hublot ouvrant de 340x140cm.<\/p>\n<p style=\"text-align: justify;\"><em>Le Carr\u00e9, le coin Navigation, les coins cuisine et toilette ont une tr\u00e8s bonne luminosit\u00e9 gr\u00e2ce au rouf panoramique et aux nombreux hublots et \u00e9coutilles.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>ISOLATION \/ FINITION DES AM\u00c9NAGEMENTS<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;isolation thermique et phonique est faite en <em>Sterofoam<\/em> de 3cm d&#8217;\u00e9paisseur, int\u00e9gr\u00e9 dans la structure de la coque, jusqu&#8217;au niveau de la flottaison et sous le pont. Cette isolation est recouverte d&#8217;un contreplaqu\u00e9 marin de 5mm sur lequel la finition est faite. Toutes les cloisons et meubles sont en contreplaqu\u00e9 de <em>teck<\/em> (double face), les moulures, coins de meubles, encadrements de portes et de hublots en <em>teck <\/em>massif. Le vaigrage du plafond est constitu\u00e9 de panneaux de contreplaqu\u00e9 de <em>ch\u00eane<\/em> clair, pos\u00e9 sur des s\u00e9parations en lattes d&#8217;<em>acajou<\/em> massif. Les dessus de comptoir et la table du carr\u00e9 sont en <em>Formica<\/em> beige. Parement de coque en <i>ska\u00ef<\/i>\u00a0blanc recouvert de vaigrage en lattes de <em>teck<\/em> massif, Le plancher au niveau du carr\u00e9, des coins cuisine et de navigation est en contreplaqu\u00e9 de <em>teck<\/em> rainur\u00e9. Le pied de la descente et le cabinet de toilette sont en panneaux de caoutchouc et le plancher de la douche est fait d&#8217;un caillebotis de <em>teck<\/em> massif.<\/p>\n<p style=\"text-align: justify;\"><em>Toutes les boiseries son recouvertes de nombreuses couches de vernis mat.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COQUE\u00a0 ET PONT Construction aluminium AGE MC 111 (AG4) en forme \u00e0 structure mixte, lisses en T\u00e9 et couples transversaux. Soudures \u00e0 l&#8217;argon Roof panoramique. Jupe arri\u00e8re latt\u00e9e de teck. Cloison avant\u00a0 \u00e9tanche. Coffre \u00e0 voile et \/ou large baille \u00e0 mouillages \u00e0 l&#8217;avant. Puits \u00e0 cha\u00eene pour deux mouillages. 2 coffres arri\u00e8res. 1 vaste &hellip; <a href=\"https:\/\/www.cotedenuits.fr\/pt\/categorie-1\/descriptif-de-cote-de-nuits\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Descriptif de C\u00f4te de Nuits<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-451","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"pt","enabled_languages":["en","es","de","fr","pt","it"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"it":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te de Nuits\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/cotedenuits22\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-11T17:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/\",\"url\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/\",\"name\":\"Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.cotedenuits.fr\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/20025-300x195.jpg\",\"datePublished\":\"2015-02-08T17:42:30+00:00\",\"dateModified\":\"2026-01-11T17:37:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.cotedenuits.fr\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/20025-300x195.jpg\",\"contentUrl\":\"http:\\\/\\\/www.cotedenuits.fr\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/20025-300x195.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/descriptif-de-cote-de-nuits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Le bateau\",\"item\":\"https:\\\/\\\/www.cotedenuits.fr\\\/categorie-1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descriptif de C\u00f4te de Nuits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cotedenuits.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cotedenuits.fr\\\/\",\"name\":\"C\u00f4te de Nuits\",\"description\":\"un Bateau, une Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cotedenuits.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/","og_locale":"pt_PT","og_type":"article","og_title":"Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits","og_url":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/","og_site_name":"C\u00f4te de Nuits","article_publisher":"http:\/\/www.facebook.com\/cotedenuits22","article_modified_time":"2026-01-11T17:37:17+00:00","og_image":[{"url":"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg","type":"","width":"","height":""}],"twitter_misc":{"Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/","url":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/","name":"Descriptif de C\u00f4te de Nuits - C\u00f4te de Nuits","isPartOf":{"@id":"https:\/\/www.cotedenuits.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/#primaryimage"},"image":{"@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg","datePublished":"2015-02-08T17:42:30+00:00","dateModified":"2026-01-11T17:37:17+00:00","breadcrumb":{"@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/#primaryimage","url":"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg","contentUrl":"http:\/\/www.cotedenuits.fr\/wp-content\/uploads\/2015\/03\/20025-300x195.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cotedenuits.fr\/categorie-1\/descriptif-de-cote-de-nuits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Le bateau","item":"https:\/\/www.cotedenuits.fr\/categorie-1\/"},{"@type":"ListItem","position":2,"name":"Descriptif de C\u00f4te de Nuits"}]},{"@type":"WebSite","@id":"https:\/\/www.cotedenuits.fr\/#website","url":"https:\/\/www.cotedenuits.fr\/","name":"C\u00f4te de Nuits","description":"un Bateau, une Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cotedenuits.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/pages\/451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":52,"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/pages\/451\/revisions"}],"predecessor-version":[{"id":1791,"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/pages\/451\/revisions\/1791"}],"up":[{"embeddable":true,"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"https:\/\/www.cotedenuits.fr\/pt\/wp-json\/wp\/v2\/media?parent=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}